{"id":32599,"date":"2022-06-06T09:00:00","date_gmt":"2022-06-06T07:00:00","guid":{"rendered":"https:\/\/www.d-velop.de\/blog\/?p=32599"},"modified":"2024-03-06T09:25:28","modified_gmt":"2024-03-06T08:25:28","slug":"entlassmanagement","status":"publish","type":"post","link":"https:\/\/www.d-velop.de\/blog\/prozesse-gestalten\/entlassmanagement\/","title":{"rendered":"Zufriedenheit im Entlassmanagement &#8211; so funktionierts mit einem digitalen Patientenportal"},"content":{"rendered":"\n<p><br>Mit dem Gesetz zur St\u00e4rkung der Versorgung in der gesetzlichen Krankenversicherung (<a href=\"https:\/\/www.bundesgesundheitsministerium.de\/service\/begriffe-von-a-z\/g\/gkv-versorgungsstaerkungsgesetz\">GKV-VSG<\/a>) in \u00a7 39 SGB V erhalten gesetzlich versicherte Patienten:innen nun den Anspruch auf ein klar geregeltes Entlassmanagement. Wir erkl\u00e4ren, wie sich ein digitales Patientenportal in den Prozess des Entlassmanagements einf\u00fcgt und welche Vorteile es bietet \u2013 f\u00fcr mehr Zufriedenheit bei Mitarbeitenden und Patienten:innen.<\/p>\n\n\n\n<div class=\"wp-block-group is-style-info-explanation\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"gesetz-zur-staerkung-der-versorgung-in-der-gesetzlichen-krankenversicherung-gkv-vsg\"><\/span>Gesetz zur St\u00e4rkung der Versorgung in der gesetzlichen Krankenversicherung | GKV-VSG<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Das <strong>Gesetz zur St\u00e4rkung der Versorgung in der gesetzlichen Krankenversicherung<\/strong> (Versorgungsst\u00e4rkungsgesetz oder GKV-VSG) zielt darauf ab, in Zukunft eine gut erreichbare medizinische Versorgung der Patientinnen und Patienten auf hohem Niveau sicherzustellen.<\/p>\n\n\n\n<p>Auch das Entlassmanagement soll in diesem Zuge klar f\u00fcr Patienten:innen geregelt werden.<\/p>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-besonderheiten-des-modernen-entlassmanagements-in-krankenhausern\"><span class=\"ez-toc-section\" id=\"besonderheiten-des-modernen-entlassmanagements-in-krankenhaeusern\"><\/span>Besonderheiten des modernen Entlassmanagements in Krankenh\u00e4usern<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Am Ende eines Krankenhausaufenthaltes steht in der Regel die \u00dcberleitung der Patienten:innen zum eigenen Hausarzt oder in eine Reha- bzw. Pflegeeinrichtung. Damit dieser \u00dcbergang reibungslos gelingt, die Anschlussversorgung gew\u00e4hrleistet ist und die Patienten:innen nicht zus\u00e4tzlich belastet werden, sind Krankenh\u00e4user heute verpflichtet, beispielsweise Verordnungen von Arznei- und Heilmitteln sowie Arbeitsunf\u00e4higkeitsbescheinigungen auszustellen.<\/p>\n\n\n\n<p>Vor Einf\u00fchrung des Gesetzes bestand diese Verpflichtung nicht, vielmehr oblag es den Patienten:innen, Rezepte und Krankschreibungen \u00fcber ihre haus\u00e4rztlichen Praxen zu beantragen. Diese Regelung konnte sich unter Umst\u00e4nden dann negativ f\u00fcr Patienten:innen auswirken, wenn sie etwa zu einem langen Wochenende entlassen wurden und der Besuch bei Haus\u00e4rzten:innen nicht mehr m\u00f6glich war. In solch einem Fall ist nun das Krankenhaus dazu angehalten die Versorgungsl\u00fccke zu schlie\u00dfen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-datenschutz-und-entlassmanagement\"><span class=\"ez-toc-section\" id=\"datenschutz-und-entlassmanagement\"><\/span>Datenschutz und Entlassmanagement<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Ziel des Entlassmanagements ist die Gew\u00e4hrleistung der bedarfsgerechten, kontinuierlichen Versorgung der Patienten im Anschluss an die Krankenhausbehandlung. Dies bedarf einer sowohl strukturierten als auch sicheren Weitergabe versorgungsrelevanter Informationen.<\/p>\n\n\n\n<p>Hierf\u00fcr ist aus Gr\u00fcnden des <a href=\"https:\/\/www.d-velop.de\/blog\/compliance\/aufbewahrungspflichten-personalunterlagen\/\">Datenschutzes<\/a> die vorherige Information und schriftliche Einwilligung der Patienten:innen erforderlich. Letztere ben\u00f6tigen Krankenh\u00e4user zur Anmeldung der Patienten:innen z.B. in Rehabilitationseinrichtungen, da hierbei medizinische Daten weitergeleitet werden.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-herausforderungen-beim-entlassmanagement-im-krankenhausalltag\"><span class=\"ez-toc-section\" id=\"herausforderungen-beim-entlassmanagement-im-krankenhausalltag\"><\/span>Herausforderungen beim Entlassmanagement im Krankenhausalltag<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Die Beachtung des Datenschutzes ist nicht die einzige Herausforderung, die sich im Krankenhausalltag stellt. Das Entlassmanagement hat patientenindividuell und teilhabeorientiert zu erfolgen. Das bedeutet auch, dass bei der Auswahl der Anschlusseinrichtungen der Wunsch der Patienten:innen zu ber\u00fccksichtigen ist.<\/p>\n\n\n\n<p>Theoretisch sind hierf\u00fcr h\u00e4ufig mehrere Gespr\u00e4che zwischen Patienten:innen und Angeh\u00f6rigen mit Mitarbeitenden aus Pflege, \u00c4rzteschaft und Sozialdienst notwendig. In der Praxis sehen sich die Krankenhausmitarbeitenden jedoch oft damit konfrontiert, dass die Patienten:innen nicht immer sofort zu sprechen sind. Gr\u00fcnde daf\u00fcr k\u00f6nnen sein:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Patienten:innen nehmen an Untersuchungen teil und k\u00f6nnen daher nicht auf ihren Zimmern angetroffen werden.<\/li>\n\n\n\n<li>Angeh\u00f6rige sind per Telefon oder E-Mail nur schwer oder gar nicht erreichbar.<\/li>\n\n\n\n<li>Volle Terminkalender aller Beteiligten verz\u00f6gern gemeinsame Termine vor Ort oder per Telefon, z.B. zwischen Sozialdienst und Angeh\u00f6rigen.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/dvelop-blog-entlassungsmanagement-Herausforderungen-infografik.png\"><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1304\" src=\"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/dvelop-blog-entlassungsmanagement-Herausforderungen-infografik.png\" alt=\"Infografik zeigt die Herausforderungen des Entlassmanagements\" class=\"wp-image-32631\" srcset=\"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/dvelop-blog-entlassungsmanagement-Herausforderungen-infografik.png 2000w, https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/dvelop-blog-entlassungsmanagement-Herausforderungen-infografik-600x391.png 600w, https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/dvelop-blog-entlassungsmanagement-Herausforderungen-infografik-1090x711.png 1090w, https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/dvelop-blog-entlassungsmanagement-Herausforderungen-infografik-768x501.png 768w, https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/dvelop-blog-entlassungsmanagement-Herausforderungen-infografik-1536x1001.png 1536w, https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/dvelop-blog-entlassungsmanagement-Herausforderungen-infografik-1920x1252.png 1920w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" \/><\/a><\/figure>\n\n\n\n<p>Diese Faktoren f\u00fchren dazu, dass wichtige Besprechungen nicht zeitnah durchgef\u00fchrt werden und Pl\u00e4tze f\u00fcr die Anschlussversorgung nicht beantragt werden k\u00f6nnen. Je l\u00e4nger sich die Prozesse des Entlassmanagements in die L\u00e4nge ziehen und je mehr diese unter Zeitdruck durchgef\u00fchrt werden m\u00fcssen, desto verunsicherter und schlechter betreut f\u00fchlen sich die Patienten:innen und desto anf\u00e4lliger f\u00fcr Fehler sind die Mitarbeitenden.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-mit-digitaler-signatur-mitarbeitende-und-patienten-innen-entlasten\"><span class=\"ez-toc-section\" id=\"mit-digitaler-signatur-mitarbeitende-und-patienten-innen-entlasten\"><\/span>Mit digitaler Signatur Mitarbeitende und Patienten:innen entlasten<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>W\u00e4hrend der Dauer des Krankenhausaufenthalts bekommen Patienten:innen eine Vielzahl unterschiedlicher Behandlungsdokumente ausgeh\u00e4ndigt, die es zu unterschreiben und verwahren gilt. In der Regel werden diese von Krankenhausmitarbeitenden angefertigt, ausgedruckt, den Patienten:innen pers\u00f6nlich \u00fcbergeben, von ihnen analog unterschrieben und dann wieder h\u00e4ndisch zur\u00fcckgegeben \u2013 oftmals \u00fcber einen Zeitraum von einigen Tagen.<\/p>\n\n\n\n<p>Die <a href=\"https:\/\/www.d-velop.de\/blog\/prozesse-gestalten\/digitale-unterschrift\/\">digitale Unterschrift<\/a>, eingebunden in das Patientenportal, vereinfacht und beschleunigt diesen Prozess ungleich mehr. Die Patienten:innen erhalten Dokumente jedweder Art direkt \u00fcber das Portal, k\u00f6nnen diese <a href=\"https:\/\/www.d-velop.de\/blog\/prozesse-gestalten\/digital-unterschreiben\/\">digital unterschreiben<\/a> und direkt wieder zur\u00fccksenden \u2013 eine enorme Zeit- und Aufwandsersparnis sowohl f\u00fcr die Patienten:innen als auch die Mitarbeitenden.<\/p>\n\n\n\n<p>Durch solch ein sicheres und strukturiertes Entlassmanagement gew\u00e4hrleisten Krankenh\u00e4user die gute Genesung und Anschlussversorgung ihrer Patienten:innen auf der einen und eine Steigerung der Zufriedenheit ihrer Mitarbeitenden auf der anderen Seite.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-kurze-digitale-wege-in-der-bereitstellung-von-patienten-innen-informationen\"><span class=\"ez-toc-section\" id=\"kurze-digitale-wege-in-der-bereitstellung-von-patienten-innen-informationen\"><\/span>Kurze digitale Wege in der Bereitstellung von Patienten:innen-Informationen<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>F\u00fcr viele Patienten:innen schlie\u00dft sich nach Ende des Krankenhausaufenthalts eine Weiterbehandlung in etwa einer Rehabilitationseinrichtung an. Um eine passende auszuw\u00e4hlen, stellen die Mitarbeitenden entsprechende Unterlagen zusammen und via Patientenportal den Patienten:innen direkt zur Verf\u00fcgung.<\/p>\n\n\n\n<p>Patienten:innen haben dann Gelegenheit, das Informationsmaterial in Ruhe durchzusehen und gegebenenfalls mit ihren Angeh\u00f6rigen zu besprechen. Um den Krankenhausmitarbeitenden eine R\u00fcckmeldung zukommen zu lassen, kann ebenfalls direkt das Patientenportal genutzt werden \u2013 schnell und bequem und ohne den unter Umst\u00e4nden langwierigen Prozess, einen gemeinsamen Termin zu vereinbaren. Andersherum erhalten Patienten:innen \u00fcber das Portal Updates \u00fcber den Anmeldestatus in ihrer Wunscheinrichtung.<\/p>\n\n\n\n<p>Selbst nachdem die Patienten:innen aus dem Krankenhaus entlassen wurden, k\u00f6nnen sie direkt und komplikationslos \u00fcber das Patientenportal erreicht werden, beispielsweise um ihnen nachtr\u00e4gliche Unterlagen zuzuschicken.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-fazit-mehr-zeit-fur-die-patienten-innen-und-eine-bessere-medizinische-versorgung\"><span class=\"ez-toc-section\" id=\"fazit-mehr-zeit-fuer-die-patienten-innen-und-eine-bessere-medizinische-versorgung\"><\/span>Fazit: Mehr Zeit f\u00fcr die Patienten:innen und eine bessere medizinische Versorgung<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Das digitale Patientenportal kommt als integraler Teil des Entlassmanagements zur Anwendung und ist die ganzheitliche L\u00f6sung f\u00fcr digitale Kommunikation in Krankenh\u00e4usern, sogar \u00fcber die Aufenthaltsdauer der Patienten:innen hinaus. Es bezieht die Patienten:innen direkt in den Prozess mit ein und gibt ihnen das sichere Gef\u00fchl, rundum gut betreut zu werden. Auch die Mitarbeitenden profitieren von verschlankten Kommunikationswegen und k\u00f6nnen ihrer Arbeit sowohl zeit- als auch ressourcenschonender nachgehen und sich besser auf die Versorgung ihrer Patienten:innen fokussieren.<\/p>\n\n\n\n<div class=\"wp-block-group is-style-cta-whitepaper\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p><strong>Die digitale Patientenakte: <\/strong>So digitalisieren Sie Prozesse in Krankenhaus &amp; Klinik<\/p>\n\n\n\n\t<div class=\"wp-block-buttons\">\n\t\t<div class=\"wp-block-button is-style-outline\">\n\t\t\t<a class=\"wp-block-button__link\" href=\"https:\/\/content.d-velop.de\/whitepaper-gesundheitswesen-patientenakte?utm_campaign=Sonstiges+-+d.velop+BLOG+-+01%2F2018&#038;utm_source=intern-blog-ger&#038;utm_medium=blogpost-entlassmanagement&#038;utm_content=button\" target=\"\">Whitepaper herunterladen<\/a>\t\t<\/div>\n\t<\/div>\n\n\t<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Mit dem Gesetz zur St\u00e4rkung der Versorgung in der gesetzlichen Krankenversicherung (GKV-VSG) in \u00a7 39 SGB V erhalten gesetzlich versicherte [&hellip;]<\/p>\n","protected":false},"author":111,"featured_media":32636,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","beyondwords_generate_audio":"","beyondwords_project_id":"","beyondwords_content_id":"","beyondwords_preview_token":"","beyondwords_player_content":"","beyondwords_player_style":"","beyondwords_language_id":"","beyondwords_title_voice_id":"","beyondwords_body_voice_id":"","beyondwords_summary_voice_id":"","beyondwords_error_message":"","beyondwords_disabled":"","beyondwords_delete_content":"","beyondwords_podcast_id":"","beyondwords_hash":"","publish_post_to_speechkit":"","speechkit_hash":"","speechkit_generate_audio":"","speechkit_project_id":"","speechkit_podcast_id":"","speechkit_error_message":"","speechkit_disabled":"","speechkit_access_key":"","speechkit_error":"","speechkit_info":"","speechkit_response":"","speechkit_retries":"","speechkit_status":"","speechkit_updated_at":"","_speechkit_link":"","_speechkit_text":""},"categories":[3],"tags":[6509],"class_list":["post-32599","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prozesse-gestalten","tag-gesundheitswesen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.6 (Yoast SEO v25.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Entlassmanagement - Zufriedenheit durch digitales Patientenportal<\/title>\n<meta name=\"description\" content=\"Entlassmanagement - Besonderheiten in Krankenh\u00e4usern \u2714 Herausforderungen im Krankenhausalltag \u2714 So funktioniert es mit einem digitalen Patientenportal \u25b6\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.d-velop.de\/blog\/prozesse-gestalten\/entlassmanagement\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zufriedenheit im Entlassmanagement - so funktionierts mit einem digitalen Patientenportal\" \/>\n<meta property=\"og:description\" content=\"Entlassmanagement - Besonderheiten in Krankenh\u00e4usern \u2714 Herausforderungen im Krankenhausalltag \u2714 So funktioniert es mit einem digitalen Patientenportal \u25b6\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.d-velop.de\/blog\/prozesse-gestalten\/entlassmanagement\/\" \/>\n<meta property=\"og:site_name\" content=\"d.velop blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/d.velop.ag\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-06T07:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-06T08:25:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/d-velop-blog-artikel-entlassmanagement-social-media.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Katja Mattejat\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@d_velop\" \/>\n<meta name=\"twitter:site\" content=\"@d_velop\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Katja Mattejat\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.d-velop.de\/blog\/prozesse-gestalten\/entlassmanagement\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.d-velop.de\/blog\/prozesse-gestalten\/entlassmanagement\/\"},\"author\":{\"name\":\"Katja Mattejat\",\"@id\":\"https:\/\/www.d-velop.de\/blog\/#\/schema\/person\/c193af8a2d574308950627146e685faa\"},\"headline\":\"Zufriedenheit im Entlassmanagement &#8211; so funktionierts mit einem digitalen Patientenportal\",\"datePublished\":\"2022-06-06T07:00:00+00:00\",\"dateModified\":\"2024-03-06T08:25:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.d-velop.de\/blog\/prozesse-gestalten\/entlassmanagement\/\"},\"wordCount\":944,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.d-velop.de\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.d-velop.de\/blog\/prozesse-gestalten\/entlassmanagement\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/dvelop-blog-entlassungsmanagement-beitragsbild.png\",\"keywords\":[\"Gesundheitswesen\"],\"articleSection\":[\"Automatisierung von Prozessen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.d-velop.de\/blog\/prozesse-gestalten\/entlassmanagement\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.d-velop.de\/blog\/prozesse-gestalten\/entlassmanagement\/\",\"url\":\"https:\/\/www.d-velop.de\/blog\/prozesse-gestalten\/entlassmanagement\/\",\"name\":\"Entlassmanagement - Zufriedenheit durch digitales Patientenportal\",\"isPartOf\":{\"@id\":\"https:\/\/www.d-velop.de\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.d-velop.de\/blog\/prozesse-gestalten\/entlassmanagement\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.d-velop.de\/blog\/prozesse-gestalten\/entlassmanagement\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/dvelop-blog-entlassungsmanagement-beitragsbild.png\",\"datePublished\":\"2022-06-06T07:00:00+00:00\",\"dateModified\":\"2024-03-06T08:25:28+00:00\",\"description\":\"Entlassmanagement - Besonderheiten in Krankenh\u00e4usern \u2714 Herausforderungen im Krankenhausalltag \u2714 So funktioniert es mit einem digitalen Patientenportal \u25b6\",\"breadcrumb\":{\"@id\":\"https:\/\/www.d-velop.de\/blog\/prozesse-gestalten\/entlassmanagement\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.d-velop.de\/blog\/prozesse-gestalten\/entlassmanagement\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.d-velop.de\/blog\/prozesse-gestalten\/entlassmanagement\/#primaryimage\",\"url\":\"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/dvelop-blog-entlassungsmanagement-beitragsbild.png\",\"contentUrl\":\"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/dvelop-blog-entlassungsmanagement-beitragsbild.png\",\"width\":2000,\"height\":666,\"caption\":\"Beitragsbild Entlassmanagement\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.d-velop.de\/blog\/prozesse-gestalten\/entlassmanagement\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.d-velop.de\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zufriedenheit im Entlassmanagement &#8211; so funktionierts mit einem digitalen Patientenportal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.d-velop.de\/blog\/#website\",\"url\":\"https:\/\/www.d-velop.de\/blog\/\",\"name\":\"d.velop blog\",\"description\":\"Digitalisierung, Dokumentenmanagement und rund um d.velop\",\"publisher\":{\"@id\":\"https:\/\/www.d-velop.de\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.d-velop.de\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.d-velop.de\/blog\/#organization\",\"name\":\"d.velop Gruppe\",\"url\":\"https:\/\/www.d-velop.de\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.d-velop.de\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2018\/12\/dvelop-blog-logo-invers.jpg\",\"contentUrl\":\"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2018\/12\/dvelop-blog-logo-invers.jpg\",\"width\":350,\"height\":350,\"caption\":\"d.velop Gruppe\"},\"image\":{\"@id\":\"https:\/\/www.d-velop.de\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/d.velop.ag\/\",\"https:\/\/x.com\/d_velop\",\"https:\/\/de.linkedin.com\/company\/d-velop\",\"https:\/\/www.xing.com\/pages\/d-velopag\",\"https:\/\/www.instagram.com\/d.velop_group\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.d-velop.de\/blog\/#\/schema\/person\/c193af8a2d574308950627146e685faa\",\"name\":\"Katja Mattejat\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.d-velop.de\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2020\/10\/katja-mattejat-d-velop-ag-150x150.jpg\",\"contentUrl\":\"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2020\/10\/katja-mattejat-d-velop-ag-150x150.jpg\",\"caption\":\"Katja Mattejat\"},\"description\":\"Marketing Manager Healthcare &amp; Welfare\",\"sameAs\":[\"https:\/\/www.d-velop.de\/\",\"https:\/\/www.linkedin.com\/in\/katja-mattejat-35b381181\/\"],\"url\":\"https:\/\/www.d-velop.de\/blog\/author\/katja-mattejat\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Entlassmanagement - Zufriedenheit durch digitales Patientenportal","description":"Entlassmanagement - Besonderheiten in Krankenh\u00e4usern \u2714 Herausforderungen im Krankenhausalltag \u2714 So funktioniert es mit einem digitalen Patientenportal \u25b6","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.d-velop.de\/blog\/prozesse-gestalten\/entlassmanagement\/","og_locale":"de_DE","og_type":"article","og_title":"Zufriedenheit im Entlassmanagement - so funktionierts mit einem digitalen Patientenportal","og_description":"Entlassmanagement - Besonderheiten in Krankenh\u00e4usern \u2714 Herausforderungen im Krankenhausalltag \u2714 So funktioniert es mit einem digitalen Patientenportal \u25b6","og_url":"https:\/\/www.d-velop.de\/blog\/prozesse-gestalten\/entlassmanagement\/","og_site_name":"d.velop blog","article_publisher":"https:\/\/www.facebook.com\/d.velop.ag\/","article_published_time":"2022-06-06T07:00:00+00:00","article_modified_time":"2024-03-06T08:25:28+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/d-velop-blog-artikel-entlassmanagement-social-media.png","type":"image\/png"}],"author":"Katja Mattejat","twitter_card":"summary_large_image","twitter_creator":"@d_velop","twitter_site":"@d_velop","twitter_misc":{"Verfasst von":"Katja Mattejat","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.d-velop.de\/blog\/prozesse-gestalten\/entlassmanagement\/#article","isPartOf":{"@id":"https:\/\/www.d-velop.de\/blog\/prozesse-gestalten\/entlassmanagement\/"},"author":{"name":"Katja Mattejat","@id":"https:\/\/www.d-velop.de\/blog\/#\/schema\/person\/c193af8a2d574308950627146e685faa"},"headline":"Zufriedenheit im Entlassmanagement &#8211; so funktionierts mit einem digitalen Patientenportal","datePublished":"2022-06-06T07:00:00+00:00","dateModified":"2024-03-06T08:25:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.d-velop.de\/blog\/prozesse-gestalten\/entlassmanagement\/"},"wordCount":944,"commentCount":0,"publisher":{"@id":"https:\/\/www.d-velop.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.d-velop.de\/blog\/prozesse-gestalten\/entlassmanagement\/#primaryimage"},"thumbnailUrl":"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/dvelop-blog-entlassungsmanagement-beitragsbild.png","keywords":["Gesundheitswesen"],"articleSection":["Automatisierung von Prozessen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.d-velop.de\/blog\/prozesse-gestalten\/entlassmanagement\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.d-velop.de\/blog\/prozesse-gestalten\/entlassmanagement\/","url":"https:\/\/www.d-velop.de\/blog\/prozesse-gestalten\/entlassmanagement\/","name":"Entlassmanagement - Zufriedenheit durch digitales Patientenportal","isPartOf":{"@id":"https:\/\/www.d-velop.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.d-velop.de\/blog\/prozesse-gestalten\/entlassmanagement\/#primaryimage"},"image":{"@id":"https:\/\/www.d-velop.de\/blog\/prozesse-gestalten\/entlassmanagement\/#primaryimage"},"thumbnailUrl":"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/dvelop-blog-entlassungsmanagement-beitragsbild.png","datePublished":"2022-06-06T07:00:00+00:00","dateModified":"2024-03-06T08:25:28+00:00","description":"Entlassmanagement - Besonderheiten in Krankenh\u00e4usern \u2714 Herausforderungen im Krankenhausalltag \u2714 So funktioniert es mit einem digitalen Patientenportal \u25b6","breadcrumb":{"@id":"https:\/\/www.d-velop.de\/blog\/prozesse-gestalten\/entlassmanagement\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.d-velop.de\/blog\/prozesse-gestalten\/entlassmanagement\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.d-velop.de\/blog\/prozesse-gestalten\/entlassmanagement\/#primaryimage","url":"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/dvelop-blog-entlassungsmanagement-beitragsbild.png","contentUrl":"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/dvelop-blog-entlassungsmanagement-beitragsbild.png","width":2000,"height":666,"caption":"Beitragsbild Entlassmanagement"},{"@type":"BreadcrumbList","@id":"https:\/\/www.d-velop.de\/blog\/prozesse-gestalten\/entlassmanagement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.d-velop.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Zufriedenheit im Entlassmanagement &#8211; so funktionierts mit einem digitalen Patientenportal"}]},{"@type":"WebSite","@id":"https:\/\/www.d-velop.de\/blog\/#website","url":"https:\/\/www.d-velop.de\/blog\/","name":"d.velop blog","description":"Digitalisierung, Dokumentenmanagement und rund um d.velop","publisher":{"@id":"https:\/\/www.d-velop.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.d-velop.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.d-velop.de\/blog\/#organization","name":"d.velop Gruppe","url":"https:\/\/www.d-velop.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.d-velop.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2018\/12\/dvelop-blog-logo-invers.jpg","contentUrl":"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2018\/12\/dvelop-blog-logo-invers.jpg","width":350,"height":350,"caption":"d.velop Gruppe"},"image":{"@id":"https:\/\/www.d-velop.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/d.velop.ag\/","https:\/\/x.com\/d_velop","https:\/\/de.linkedin.com\/company\/d-velop","https:\/\/www.xing.com\/pages\/d-velopag","https:\/\/www.instagram.com\/d.velop_group\/"]},{"@type":"Person","@id":"https:\/\/www.d-velop.de\/blog\/#\/schema\/person\/c193af8a2d574308950627146e685faa","name":"Katja Mattejat","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.d-velop.de\/blog\/#\/schema\/person\/image\/","url":"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2020\/10\/katja-mattejat-d-velop-ag-150x150.jpg","contentUrl":"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2020\/10\/katja-mattejat-d-velop-ag-150x150.jpg","caption":"Katja Mattejat"},"description":"Marketing Manager Healthcare &amp; Welfare","sameAs":["https:\/\/www.d-velop.de\/","https:\/\/www.linkedin.com\/in\/katja-mattejat-35b381181\/"],"url":"https:\/\/www.d-velop.de\/blog\/author\/katja-mattejat\/"}]}},"_links":{"self":[{"href":"https:\/\/www.d-velop.de\/blog\/wp-json\/wp\/v2\/posts\/32599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.d-velop.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.d-velop.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.d-velop.de\/blog\/wp-json\/wp\/v2\/users\/111"}],"replies":[{"embeddable":true,"href":"https:\/\/www.d-velop.de\/blog\/wp-json\/wp\/v2\/comments?post=32599"}],"version-history":[{"count":2,"href":"https:\/\/www.d-velop.de\/blog\/wp-json\/wp\/v2\/posts\/32599\/revisions"}],"predecessor-version":[{"id":47269,"href":"https:\/\/www.d-velop.de\/blog\/wp-json\/wp\/v2\/posts\/32599\/revisions\/47269"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.d-velop.de\/blog\/wp-json\/wp\/v2\/media\/32636"}],"wp:attachment":[{"href":"https:\/\/www.d-velop.de\/blog\/wp-json\/wp\/v2\/media?parent=32599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.d-velop.de\/blog\/wp-json\/wp\/v2\/categories?post=32599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.d-velop.de\/blog\/wp-json\/wp\/v2\/tags?post=32599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}