{"id":32778,"date":"2022-06-11T10:00:00","date_gmt":"2022-06-11T08:00:00","guid":{"rendered":"https:\/\/www.d-velop.de\/blog\/?p=32778"},"modified":"2023-03-06T12:09:58","modified_gmt":"2023-03-06T11:09:58","slug":"it-transformation","status":"publish","type":"post","link":"https:\/\/www.d-velop.de\/blog\/digitaler-wandel\/it-transformation\/","title":{"rendered":"In vier gro\u00dfen Schritten zur IT-Transformation \u2013 Wie du deine interne IT fit f\u00fcr die digitale Zukunft machst"},"content":{"rendered":"\n<p>\u00dcberlastete Mitarbeitende in der IT-Abteilung, Anwender:innen im Unternehmen, die schneller neue Anforderungen einkippen, als mit der aktuellen Organisation umzusetzen sind. Unzufriedenheit mit der Qualit\u00e4t der L\u00f6sungen, fehlende Priorisierung \u2026 kommt dir das bekannt vor? Unternehmenswachstum und organisatorische Ver\u00e4nderungen stellen auch die interne IT vor immer gr\u00f6\u00dfere Herausforderungen. H\u00f6chste Zeit, etwas zu ver\u00e4ndern, hin zu mehr Transparenz und gr\u00f6\u00dferer Messbarkeit. Nur wie? Genau damit haben wir uns auch bei der d.velop besch\u00e4ftigt: Wie k\u00f6nnen wir die IT-Transformation schaffen? Wir zeigen hier einen Leitfaden aus der Praxis, der sicher auch deiner IT im Unternehmen oder der Organisation helfen wird, fit f\u00fcr die digitale Zukunft zu werden. <\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Ich wei\u00df nicht, ob es besser wird, wenn es anders wird. Aber es muss anders werden, wenn es besser werden soll.<\/p><cite>Georg Christoph Lichtenberg<\/cite><\/blockquote><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"herausforderungen-der-it\"><\/span>Herausforderungen der IT<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Oftmals hat die IT mit denselben Herausforderungen zu k\u00e4mpfen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Wir verstehen nicht das Problem der Anwendenden<\/li>\n\n\n\n<li>Wir definieren das Ergebnis ohne Commitment<\/li>\n\n\n\n<li>Wir wissen nicht, wann ein Projekt beendet ist<\/li>\n\n\n\n<li>Das Vorgehen f\u00fcr eine Priorisierung fehlt<\/li>\n\n\n\n<li>Wir k\u00f6nnen das Projektergebnis nicht messen<\/li>\n\n\n\n<li>Die Umsetzungszeit l\u00e4uft uns davon<\/li>\n\n\n\n<li>Der Umsetzungsaufwand wird (fast) immer zu niedrig gesch\u00e4tzt<\/li>\n\n\n\n<li>Projektmanagement-Methoden werden kaum verwendet<\/li>\n<\/ul>\n\n\n\n<p>Es gilt also, hier strukturiert Abhilfe zu schaffen und \u00fcber einheitliche Metriken gezielte Ma\u00dfnahmen zu ergreifen, deren Erfolg messbar ist. Folgende vier m\u00f6glichen Schritte k\u00f6nnen dazu beitragen, die IT-Transformation voranzutreiben und so die Organisation nachhaltig zu ver\u00e4ndern. W\u00e4hrend dieses Transformationsprozesses hat uns Hogir von <a rel=\"noreferrer noopener\" href=\"http:\/\/www.lmx.eu\/\" target=\"_blank\">lmx <\/a>begleitet und intensiv unterst\u00fctzt.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"aller-anfang-sind-rahmenbedingungen\"><\/span>Aller Anfang sind Rahmenbedingungen<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Um am Ende die richtigen Ma\u00dfnahmen zu ergreifen, haben wir Rahmenbedingungen definiert und dabei im Kern angefangen. Der Kern ist die Organisation und die IT-Prozesse schlie\u00dfen sich an. Denn bevor wir eine Verbesserung einf\u00fchren, m\u00fcssen wir erst einmal begreifen, wo wir gerade stehen, wie wir arbeiten und was unser eigentliches Ziel ist. Daraus ergeben sich Metriken, deren Ergebnisse mit den passenden Ma\u00dfnahmen verbessert werden.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/it-transformation-rahmenbedingungen.png\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1090\" height=\"462\" src=\"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/it-transformation-rahmenbedingungen-1090x462.png\" alt=\"IT Transformation Rahmenbedingungen definieren\" class=\"wp-image-32806\" srcset=\"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/it-transformation-rahmenbedingungen-1090x462.png 1090w, https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/it-transformation-rahmenbedingungen-600x254.png 600w, https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/it-transformation-rahmenbedingungen-768x325.png 768w, https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/it-transformation-rahmenbedingungen-1536x650.png 1536w, https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/it-transformation-rahmenbedingungen-1920x813.png 1920w, https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/it-transformation-rahmenbedingungen.png 2000w\" sizes=\"auto, (max-width: 1090px) 100vw, 1090px\" \/><\/a><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"partizipatorischer-veraenderungsprozess-durch-foerdernde-rahmenbedingungen\"><\/span>Partizipatorischer Ver\u00e4nderungsprozess durch f\u00f6rdernde Rahmenbedingungen<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Bei Ver\u00e4nderungsprozessen ist es wichtig, Rahmenbedingungen zu setzen, die es betroffenen Mitarbeitenden erm\u00f6glichen an der Ver\u00e4nderung mitzuwirken. Man spricht hier von <strong>f\u00f6rdernden Rahmenbedingungen<\/strong> (eng. Enabling Constraints), die mehr Raum f\u00fcr geeignete L\u00f6sungen schaffen. Eine f\u00f6rdernde Rahmenbedingung f\u00fcr ein IT-Team k\u00f6nnte beispielsweise sein: &#8222;Wir stimmen uns in regelm\u00e4\u00dfigen Abst\u00e4nden \u00fcber unseren Entwicklungsfortschritt ab und passen die Planung auf Basis neuer Erkenntnisse an!&#8220;. Im Gegensatz stehen dazu <strong>regelorientierte Rahmenbedingungen<\/strong> (eng. Governing Constraints), die den L\u00f6sungsraum kleiner gestalten, jedoch leichter zu befolgen sind. Eine regelorientierte Rahmenbedingung f\u00fcr ein IT-Team k\u00f6nnte beispielsweise sein: &#8222;Alle zwei Wochen stimmen wir uns \u00fcber unseren Entwicklungsfortschritt und t\u00e4glich \u00fcber unsere Aufgaben ab.&#8220;<\/p>\n\n\n\n<p>Die st\u00e4rkere Einschr\u00e4nkung bei den regelorientierten Rahmenbedingungen birgt das Risiko, zu fr\u00fch eine vermeintliche L\u00f6sung zu definieren, die die urs\u00e4chlichen Probleme nicht l\u00f6st.<\/p>\n\n\n\n<p>F\u00fcr die Umsetzung der Ver\u00e4nderung haben wir uns daher darauf fokussiert, f\u00f6rdernde Rahmenbedingungen festzulegen, die es den Mitarbeitenden erm\u00f6glichen, die beste L\u00f6sung f\u00fcr sich zu finden. Konkret haben wir die vier folgenden Rahmenbedingungen (auf Basis der Kanban Prinzipien) definiert:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Beginne mit dem, was du gerade tust<\/li>\n\n\n\n<li>Verfolge inkrementelle und evolution\u00e4re Ver\u00e4nderung<\/li>\n\n\n\n<li>Ber\u00fccksichtige aktuelle Rollen, Prozesse und Verantwortlichkeiten<\/li>\n\n\n\n<li>F\u00f6rdere F\u00fchrung auf allen Ebenen der Organisation<\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"schritt-1-prozesse-definieren\"><\/span>Schritt 1: Prozesse definieren<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Zun\u00e4chst haben wir versucht, das erste Prinzip zu befolgen und die relevantesten Prozesse zu identifizieren und zu definieren. Dabei haben wir 3 relevante Prozesse identifiziert:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Incidents<\/li>\n\n\n\n<li>Change Requests<\/li>\n\n\n\n<li>Projekte<\/li>\n<\/ol>\n\n\n\n<p>Die Idee, diese Prozesse gemeinsam zu definieren, stie\u00df zun\u00e4chst nicht auf die volle Zustimmung der Mitarbeitenden: \u201eProzesse brauchen wir nicht zu defninieren, die kennen wir seit Jahren\u201c, so die Aussage der IT-Mitarbeitenden. Umso erstaunlicher war die Erfahrung in einem gemeinsamen Workshop, die drei Prozesse gemeinsam zu designen. Zwischen den Mitarbeitenden gab es relativ viel Abstimmungsbedarf \u00fcber den Ablauf der jeweiligen Prozesse, sodass wesentlich mehr Zeit ben\u00f6tigt wurde, um einen Konsens zum Prozessdesign zu erarbeiten. Besonders spannend: Der simpelste Prozess f\u00fcr das Incident-Management beanspruchte die meiste Gestaltungszeit.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/it-transformation-prozesse-definieren.png\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1090\" height=\"477\" src=\"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/it-transformation-prozesse-definieren-1090x477.png\" alt=\"IT Transformation Prozesse definieren\" class=\"wp-image-32805\" srcset=\"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/it-transformation-prozesse-definieren-1090x477.png 1090w, https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/it-transformation-prozesse-definieren-600x263.png 600w, https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/it-transformation-prozesse-definieren-768x336.png 768w, https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/it-transformation-prozesse-definieren-1536x673.png 1536w, https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/it-transformation-prozesse-definieren-1920x841.png 1920w, https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/it-transformation-prozesse-definieren.png 2000w\" sizes=\"auto, (max-width: 1090px) 100vw, 1090px\" \/><\/a><\/figure>\n\n\n\n<p>Dies war eine relevante Erkenntnis f\u00fcr die Workshopteilnehmer und hat zu einigen &#8222;AHA&#8220;-Momenten bei den Mitarbeitenden gef\u00fchrt. F\u00fcr den Ver\u00e4nderungsprozess war das sehr wichtig, weil wir damit das Bewusstsein f\u00fcr die Relevanz der Ver\u00e4nderung geschaffen haben.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"schritt-2-spielfeld-definieren\"><\/span>Schritt 2: Spielfeld definieren<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Die meisten Mitarbeitenden wurden aufgrund ihrer Expertise in allen Prozessen involviert. Jedoch erfordert jeder Prozess einen eigenen Arbeitsmodus, sodass ein st\u00e4ndiger Wechsel zwischen den Modi die Mitarbeitenden vor gro\u00dfe Herausforderungen stellt. Das gilt auch f\u00fcr die IT-Transformation. <br>Wir haben &#8222;Laufen&#8220; als Metapher verwendet, um diese Problematik hervorzuheben:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Incidents: Sprint-Modus<\/li>\n\n\n\n<li>Change Requests: Langstrecke-Modus<\/li>\n\n\n\n<li>Projekte: Marathon-Modus<\/li>\n<\/ol>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/it-transformation-spielfeld-definieren.png\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1090\" height=\"361\" src=\"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/it-transformation-spielfeld-definieren-1090x361.png\" alt=\"Das Spielfeld definieren\" class=\"wp-image-32807\" srcset=\"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/it-transformation-spielfeld-definieren-1090x361.png 1090w, https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/it-transformation-spielfeld-definieren-600x199.png 600w, https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/it-transformation-spielfeld-definieren-768x255.png 768w, https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/it-transformation-spielfeld-definieren-1536x509.png 1536w, https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/it-transformation-spielfeld-definieren-1920x636.png 1920w, https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/it-transformation-spielfeld-definieren.png 2000w\" sizes=\"auto, (max-width: 1090px) 100vw, 1090px\" \/><\/a><\/figure>\n\n\n\n<p>Manche Mitarbeitende sind gut im Sprint, wobei sie in m\u00f6glichst kurzer Zeit mit gr\u00f6\u00dftm\u00f6glicher Geschwindigkeit Aufgaben erledigen. Andere sind eher als Langstreckenl\u00e4ufer:in berufen, dazu geh\u00f6ren Querfeldein- und Crossl\u00e4ufe. Die Aufgabe dauert etwas l\u00e4nger und ist unspezifischer. Wieder andere sind begeisterte Marathonl\u00e4ufer:innen. Mit ihrer langj\u00e4hrigen Erfahrung k\u00f6nnen sie die l\u00e4ngsten Distanzen \u00fcberwinden. Analog zu diesen Sportarten haben wir die IT-Organisation aufgestellt. Zu den Sprints geh\u00f6ren Incidents und Service Request, zu der Langstrecke Change Requests und zum Marathon gro\u00dfe Projekte.<\/p>\n\n\n\n<p>Mithilfe dieses Spielfelds k\u00f6nnen sich Allrounder fokussieren und sich auf eine Disziplin konzentrieren.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Relevante Metriken definieren<\/h3>\n\n\n\n<p>Beim Laufen ist die ben\u00f6tigte Zeit der relevanteste Wert, um den Erfolg zu definieren.<br>F\u00fcr drei Prozesse haben wir relevante Metriken definiert, die Transparenz dar\u00fcber geben, wie gut der Prozess l\u00e4uft. F\u00fcr den Change Request Prozess wurde die folgende Erfolgsmetrik definiert: &#8222;Wenn priorisiert und f\u00fcr einen Sprint eingeplant, sollte der Change Request innerhalb eines Sprints abgeschlossen werden!&#8220;<\/p>\n\n\n\n<p>Mithilfe von Kontrolldiagrammen und kumulierten Flussdiagrammen f\u00fchren wir jetzt in regelm\u00e4\u00dfigen Abst\u00e4nden quantitative Analysen \u00fcber die Performance durch.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Anforderungen strukturiert aufnehmen<\/h3>\n\n\n\n<p>Im Anschluss an die Prozessdefinitionen sind die zentralen Eigenschaften einer neuen Anforderung\/ eines neuen Themas festzuhalten. Ein strukturiertes Themen-Canvas ist eine gute Grundlage, um als IT-Mitarbeitender mit den Anfordernden gemeinsam die wichtigen Punkte zum Ziel des Themas, Problembeschreibung, zur Erwartungshaltung und zur Priorisierung zu erarbeiten.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/IT-Transformation-Anforderungen-Template.png\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"994\" height=\"1090\" src=\"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/IT-Transformation-Anforderungen-Template-994x1090.png\" alt=\"\" class=\"wp-image-32837\" srcset=\"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/IT-Transformation-Anforderungen-Template-994x1090.png 994w, https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/IT-Transformation-Anforderungen-Template-547x600.png 547w, https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/IT-Transformation-Anforderungen-Template-768x842.png 768w, https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/IT-Transformation-Anforderungen-Template-1401x1536.png 1401w, https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/IT-Transformation-Anforderungen-Template-1868x2048.png 1868w, https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/IT-Transformation-Anforderungen-Template-1920x2105.png 1920w, https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/IT-Transformation-Anforderungen-Template.png 2000w\" sizes=\"auto, (max-width: 994px) 100vw, 994px\" \/><\/a><\/figure>\n\n\n\n<p>Die Festlegung der Projektkategorie und der Metriken st\u00e4rken das Commitment im Team.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"schritt-3-massnahmen-ableiten\"><\/span>Schritt 3: Ma\u00dfnahmen ableiten<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Voraussetzung f\u00fcr eine verl\u00e4ssliche Umsetzungszeit ist die Kapazit\u00e4tsplanung.<\/p>\n\n\n\n<p>In einer gewachsenen IT-Abteilung werden oft zu viele Aufgaben gleichzeitig bearbeitet, was zur Folge hat, dass der Fokus auf die vereinbarte Projektumsetzung verloren geht. Finde heraus, welche Mitarbeitenden viele verschiedene Aufgaben bearbeiten, denn das kostet R\u00fcstzeit.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/it-transformation-massnahmen-ableiten.png\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1090\" height=\"1080\" src=\"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/it-transformation-massnahmen-ableiten-1090x1080.png\" alt=\"IT Transformation Ma\u00dfnahmen ableiten\" class=\"wp-image-32804\" srcset=\"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/it-transformation-massnahmen-ableiten-1090x1080.png 1090w, https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/it-transformation-massnahmen-ableiten-600x595.png 600w, https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/it-transformation-massnahmen-ableiten-768x761.png 768w, https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/it-transformation-massnahmen-ableiten-1536x1522.png 1536w, https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/it-transformation-massnahmen-ableiten-1920x1903.png 1920w, https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/it-transformation-massnahmen-ableiten.png 2000w\" sizes=\"auto, (max-width: 1090px) 100vw, 1090px\" \/><\/a><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Ma\u00dfnahmen, die wir im Rahmen der IT-Transformation umgesetzt haben<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Herausforderung von Task-Switching darstellen<\/li>\n\n\n\n<li>Transparenz \u00fcber Engpass schaffen<\/li>\n\n\n\n<li>Fokussierung einf\u00fchren<\/li>\n\n\n\n<li>WIP Limit einf\u00fchren<\/li>\n\n\n\n<li>Unterst\u00fctzung bei der Problembeschreibung<\/li>\n\n\n\n<li>gemeinsame Festlegung der Akzeptanzkriterien<\/li>\n\n\n\n<li>gemeinsame Bewertung<\/li>\n\n\n\n<li>Zusammenarbeit auf Augenh\u00f6he<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"schritt-4-kontinuierlichen-verbesserungsprozess-etablieren\"><\/span>Schritt 4: Kontinuierlichen Verbesserungsprozess etablieren<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Nachdem wir die Basis f\u00fcr eine erfolgreiche Ver\u00e4nderung gelegt hatten, ging es darum, einen kontinuierlichen Verbesserungsprozess (KVP) zu etablieren. Dies ist der wichtigste Schritt bei jeglichen Ver\u00e4nderungsprozessen. Hat man einmal einen KVP etabliert, wird \u00fcber kurz oder lang die Zusammenarbeit effektiver und effizienter in einer Organisationseinheit. Innerhalb unserer Organisation hat sich freiwillig eine Gruppe von Mitarbeitenden gefunden, die in regelm\u00e4\u00dfigen Abst\u00e4nden Verbesserungsma\u00dfnahmen definiert, umsetzt und deren Erfolgsgrad misst.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"der-erste-schritt-ist-einen-zu-tun\"><\/span>Der erste Schritt ist, einen zu tun<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Wenn du dich in der IT als Dienstleister f\u00fcr deine Mitarbeitenden siehst, und das solltest du wirklich tun und auch so f\u00fchlen, muss vor allem die Zusammenarbeit auf Augenh\u00f6he im Mittelpunkt stehen. Vor allem, wenn es um die genaue Definition der Anforderungen und die Nachvollziehbarkeit der Umsetzung geht. Die oben beschriebenen Punkte k\u00f6nnen helfen, die gesamte interne IT von Grund auf zu modernisieren, zukunftstr\u00e4chtig aufzustellen und zugleich die Zusammenarbeit mit allen Stakeholdern zu verbessern. Dann sind auch alle Beteiligten wesentlich zufriedener. Und darauf kommt es an.<\/p>\n\n\n\n<p><br>Trau dich, wage den ersten Schritt. Wir von d.velop unterst\u00fctzen gern mit unseren Erfahrungen unserer eigenen IT-Transformation. Ein hartes St\u00fcck Arbeit, das aber schon jetzt Fr\u00fcchte tr\u00e4gt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00dcberlastete Mitarbeitende in der IT-Abteilung, Anwender:innen im Unternehmen, die schneller neue Anforderungen einkippen, als mit der aktuellen Organisation umzusetzen sind. [&hellip;]<\/p>\n","protected":false},"author":189,"featured_media":32784,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","beyondwords_generate_audio":"","beyondwords_project_id":"","beyondwords_content_id":"","beyondwords_preview_token":"","beyondwords_player_content":"","beyondwords_player_style":"","beyondwords_language_id":"","beyondwords_title_voice_id":"","beyondwords_body_voice_id":"","beyondwords_summary_voice_id":"","beyondwords_error_message":"","beyondwords_disabled":"","beyondwords_delete_content":"","beyondwords_podcast_id":"","beyondwords_hash":"","publish_post_to_speechkit":"","speechkit_hash":"","speechkit_generate_audio":"","speechkit_project_id":"","speechkit_podcast_id":"","speechkit_error_message":"","speechkit_disabled":"","speechkit_access_key":"","speechkit_error":"","speechkit_info":"","speechkit_response":"","speechkit_retries":"","speechkit_status":"","speechkit_updated_at":"","_speechkit_link":"","_speechkit_text":""},"categories":[5],"tags":[],"class_list":["post-32778","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-digitaler-wandel"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.6 (Yoast SEO v25.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>In vier gro\u00dfen Schritten zur IT Transformation | d.velop blog<\/title>\n<meta name=\"description\" content=\"Die IT hat oft mit denselben Herausforderungen zu k\u00e4mpfen. Wie die IT-Transformation in 4 Schritten gelingen kann? \u2714 Erfahre mehr in diesem Blogartikel \u27a4\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.d-velop.de\/blog\/digitaler-wandel\/it-transformation\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"In vier gro\u00dfen Schritten zur IT-Transformation\" \/>\n<meta property=\"og:description\" content=\"Die IT hat oft mit denselben Herausforderungen zu k\u00e4mpfen. Wie die IT-Transformation in 4 Schritten gelingen kann? \u2714 Erfahre mehr in diesem Blogartikel \u27a4\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.d-velop.de\/blog\/digitaler-wandel\/it-transformation\/\" \/>\n<meta property=\"og:site_name\" content=\"d.velop blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/d.velop.ag\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-11T08:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-06T11:09:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/d-velop-blog-artikel-it-transformation-social-media.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Anja Bornmann-Reske\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"In vier gro\u00dfen Schritten zur IT-Transformation \u2013 Wie du deine interne IT fit f\u00fcr die digitale Zukunft machst\" \/>\n<meta name=\"twitter:creator\" content=\"@d_velop\" \/>\n<meta name=\"twitter:site\" content=\"@d_velop\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Anja Bornmann-Reske\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.d-velop.de\/blog\/digitaler-wandel\/it-transformation\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.d-velop.de\/blog\/digitaler-wandel\/it-transformation\/\"},\"author\":{\"name\":\"Anja Bornmann-Reske\",\"@id\":\"https:\/\/www.d-velop.de\/blog\/#\/schema\/person\/36838ebae60dc4364050b60bfebe3028\"},\"headline\":\"In vier gro\u00dfen Schritten zur IT-Transformation \u2013 Wie du deine interne IT fit f\u00fcr die digitale Zukunft machst\",\"datePublished\":\"2022-06-11T08:00:00+00:00\",\"dateModified\":\"2023-03-06T11:09:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.d-velop.de\/blog\/digitaler-wandel\/it-transformation\/\"},\"wordCount\":1362,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.d-velop.de\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.d-velop.de\/blog\/digitaler-wandel\/it-transformation\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/dvelop-blog-it-transformation-beitragsbild.jpg\",\"articleSection\":[\"Digitaler Wandel\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.d-velop.de\/blog\/digitaler-wandel\/it-transformation\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.d-velop.de\/blog\/digitaler-wandel\/it-transformation\/\",\"url\":\"https:\/\/www.d-velop.de\/blog\/digitaler-wandel\/it-transformation\/\",\"name\":\"In vier gro\u00dfen Schritten zur IT Transformation | d.velop blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.d-velop.de\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.d-velop.de\/blog\/digitaler-wandel\/it-transformation\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.d-velop.de\/blog\/digitaler-wandel\/it-transformation\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/dvelop-blog-it-transformation-beitragsbild.jpg\",\"datePublished\":\"2022-06-11T08:00:00+00:00\",\"dateModified\":\"2023-03-06T11:09:58+00:00\",\"description\":\"Die IT hat oft mit denselben Herausforderungen zu k\u00e4mpfen. Wie die IT-Transformation in 4 Schritten gelingen kann? \u2714 Erfahre mehr in diesem Blogartikel \u27a4\",\"breadcrumb\":{\"@id\":\"https:\/\/www.d-velop.de\/blog\/digitaler-wandel\/it-transformation\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.d-velop.de\/blog\/digitaler-wandel\/it-transformation\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.d-velop.de\/blog\/digitaler-wandel\/it-transformation\/#primaryimage\",\"url\":\"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/dvelop-blog-it-transformation-beitragsbild.jpg\",\"contentUrl\":\"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/dvelop-blog-it-transformation-beitragsbild.jpg\",\"width\":2000,\"height\":666,\"caption\":\"IT Transformation Beitragsbild\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.d-velop.de\/blog\/digitaler-wandel\/it-transformation\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.d-velop.de\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"In vier gro\u00dfen Schritten zur IT-Transformation \u2013 Wie du deine interne IT fit f\u00fcr die digitale Zukunft machst\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.d-velop.de\/blog\/#website\",\"url\":\"https:\/\/www.d-velop.de\/blog\/\",\"name\":\"d.velop blog\",\"description\":\"Digitalisierung, Dokumentenmanagement und rund um d.velop\",\"publisher\":{\"@id\":\"https:\/\/www.d-velop.de\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.d-velop.de\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.d-velop.de\/blog\/#organization\",\"name\":\"d.velop Gruppe\",\"url\":\"https:\/\/www.d-velop.de\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.d-velop.de\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2018\/12\/dvelop-blog-logo-invers.jpg\",\"contentUrl\":\"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2018\/12\/dvelop-blog-logo-invers.jpg\",\"width\":350,\"height\":350,\"caption\":\"d.velop Gruppe\"},\"image\":{\"@id\":\"https:\/\/www.d-velop.de\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/d.velop.ag\/\",\"https:\/\/x.com\/d_velop\",\"https:\/\/de.linkedin.com\/company\/d-velop\",\"https:\/\/www.xing.com\/pages\/d-velopag\",\"https:\/\/www.instagram.com\/d.velop_group\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.d-velop.de\/blog\/#\/schema\/person\/36838ebae60dc4364050b60bfebe3028\",\"name\":\"Anja Bornmann-Reske\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.d-velop.de\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/anja-bornmann-reske-dvelop-210x210.jpg\",\"contentUrl\":\"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/anja-bornmann-reske-dvelop-210x210.jpg\",\"caption\":\"Anja Bornmann-Reske\"},\"description\":\"Senior Manager IT &amp; Process Management\",\"sameAs\":[\"https:\/\/www.d-velop.de\",\"https:\/\/www.linkedin.com\/in\/anja-bornmann-reske-07844074\/\"],\"url\":\"https:\/\/www.d-velop.de\/blog\/author\/anja-bornmann-reske\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"In vier gro\u00dfen Schritten zur IT Transformation | d.velop blog","description":"Die IT hat oft mit denselben Herausforderungen zu k\u00e4mpfen. Wie die IT-Transformation in 4 Schritten gelingen kann? \u2714 Erfahre mehr in diesem Blogartikel \u27a4","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.d-velop.de\/blog\/digitaler-wandel\/it-transformation\/","og_locale":"de_DE","og_type":"article","og_title":"In vier gro\u00dfen Schritten zur IT-Transformation","og_description":"Die IT hat oft mit denselben Herausforderungen zu k\u00e4mpfen. Wie die IT-Transformation in 4 Schritten gelingen kann? \u2714 Erfahre mehr in diesem Blogartikel \u27a4","og_url":"https:\/\/www.d-velop.de\/blog\/digitaler-wandel\/it-transformation\/","og_site_name":"d.velop blog","article_publisher":"https:\/\/www.facebook.com\/d.velop.ag\/","article_published_time":"2022-06-11T08:00:00+00:00","article_modified_time":"2023-03-06T11:09:58+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/d-velop-blog-artikel-it-transformation-social-media.png","type":"image\/png"}],"author":"Anja Bornmann-Reske","twitter_card":"summary_large_image","twitter_title":"In vier gro\u00dfen Schritten zur IT-Transformation \u2013 Wie du deine interne IT fit f\u00fcr die digitale Zukunft machst","twitter_creator":"@d_velop","twitter_site":"@d_velop","twitter_misc":{"Verfasst von":"Anja Bornmann-Reske","Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.d-velop.de\/blog\/digitaler-wandel\/it-transformation\/#article","isPartOf":{"@id":"https:\/\/www.d-velop.de\/blog\/digitaler-wandel\/it-transformation\/"},"author":{"name":"Anja Bornmann-Reske","@id":"https:\/\/www.d-velop.de\/blog\/#\/schema\/person\/36838ebae60dc4364050b60bfebe3028"},"headline":"In vier gro\u00dfen Schritten zur IT-Transformation \u2013 Wie du deine interne IT fit f\u00fcr die digitale Zukunft machst","datePublished":"2022-06-11T08:00:00+00:00","dateModified":"2023-03-06T11:09:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.d-velop.de\/blog\/digitaler-wandel\/it-transformation\/"},"wordCount":1362,"commentCount":0,"publisher":{"@id":"https:\/\/www.d-velop.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.d-velop.de\/blog\/digitaler-wandel\/it-transformation\/#primaryimage"},"thumbnailUrl":"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/dvelop-blog-it-transformation-beitragsbild.jpg","articleSection":["Digitaler Wandel"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.d-velop.de\/blog\/digitaler-wandel\/it-transformation\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.d-velop.de\/blog\/digitaler-wandel\/it-transformation\/","url":"https:\/\/www.d-velop.de\/blog\/digitaler-wandel\/it-transformation\/","name":"In vier gro\u00dfen Schritten zur IT Transformation | d.velop blog","isPartOf":{"@id":"https:\/\/www.d-velop.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.d-velop.de\/blog\/digitaler-wandel\/it-transformation\/#primaryimage"},"image":{"@id":"https:\/\/www.d-velop.de\/blog\/digitaler-wandel\/it-transformation\/#primaryimage"},"thumbnailUrl":"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/dvelop-blog-it-transformation-beitragsbild.jpg","datePublished":"2022-06-11T08:00:00+00:00","dateModified":"2023-03-06T11:09:58+00:00","description":"Die IT hat oft mit denselben Herausforderungen zu k\u00e4mpfen. Wie die IT-Transformation in 4 Schritten gelingen kann? \u2714 Erfahre mehr in diesem Blogartikel \u27a4","breadcrumb":{"@id":"https:\/\/www.d-velop.de\/blog\/digitaler-wandel\/it-transformation\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.d-velop.de\/blog\/digitaler-wandel\/it-transformation\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.d-velop.de\/blog\/digitaler-wandel\/it-transformation\/#primaryimage","url":"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/dvelop-blog-it-transformation-beitragsbild.jpg","contentUrl":"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/dvelop-blog-it-transformation-beitragsbild.jpg","width":2000,"height":666,"caption":"IT Transformation Beitragsbild"},{"@type":"BreadcrumbList","@id":"https:\/\/www.d-velop.de\/blog\/digitaler-wandel\/it-transformation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.d-velop.de\/blog\/"},{"@type":"ListItem","position":2,"name":"In vier gro\u00dfen Schritten zur IT-Transformation \u2013 Wie du deine interne IT fit f\u00fcr die digitale Zukunft machst"}]},{"@type":"WebSite","@id":"https:\/\/www.d-velop.de\/blog\/#website","url":"https:\/\/www.d-velop.de\/blog\/","name":"d.velop blog","description":"Digitalisierung, Dokumentenmanagement und rund um d.velop","publisher":{"@id":"https:\/\/www.d-velop.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.d-velop.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.d-velop.de\/blog\/#organization","name":"d.velop Gruppe","url":"https:\/\/www.d-velop.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.d-velop.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2018\/12\/dvelop-blog-logo-invers.jpg","contentUrl":"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2018\/12\/dvelop-blog-logo-invers.jpg","width":350,"height":350,"caption":"d.velop Gruppe"},"image":{"@id":"https:\/\/www.d-velop.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/d.velop.ag\/","https:\/\/x.com\/d_velop","https:\/\/de.linkedin.com\/company\/d-velop","https:\/\/www.xing.com\/pages\/d-velopag","https:\/\/www.instagram.com\/d.velop_group\/"]},{"@type":"Person","@id":"https:\/\/www.d-velop.de\/blog\/#\/schema\/person\/36838ebae60dc4364050b60bfebe3028","name":"Anja Bornmann-Reske","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.d-velop.de\/blog\/#\/schema\/person\/image\/","url":"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/anja-bornmann-reske-dvelop-210x210.jpg","contentUrl":"https:\/\/www.d-velop.de\/blog\/wp-content\/uploads\/2022\/06\/anja-bornmann-reske-dvelop-210x210.jpg","caption":"Anja Bornmann-Reske"},"description":"Senior Manager IT &amp; Process Management","sameAs":["https:\/\/www.d-velop.de","https:\/\/www.linkedin.com\/in\/anja-bornmann-reske-07844074\/"],"url":"https:\/\/www.d-velop.de\/blog\/author\/anja-bornmann-reske\/"}]}},"_links":{"self":[{"href":"https:\/\/www.d-velop.de\/blog\/wp-json\/wp\/v2\/posts\/32778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.d-velop.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.d-velop.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.d-velop.de\/blog\/wp-json\/wp\/v2\/users\/189"}],"replies":[{"embeddable":true,"href":"https:\/\/www.d-velop.de\/blog\/wp-json\/wp\/v2\/comments?post=32778"}],"version-history":[{"count":1,"href":"https:\/\/www.d-velop.de\/blog\/wp-json\/wp\/v2\/posts\/32778\/revisions"}],"predecessor-version":[{"id":33071,"href":"https:\/\/www.d-velop.de\/blog\/wp-json\/wp\/v2\/posts\/32778\/revisions\/33071"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.d-velop.de\/blog\/wp-json\/wp\/v2\/media\/32784"}],"wp:attachment":[{"href":"https:\/\/www.d-velop.de\/blog\/wp-json\/wp\/v2\/media?parent=32778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.d-velop.de\/blog\/wp-json\/wp\/v2\/categories?post=32778"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.d-velop.de\/blog\/wp-json\/wp\/v2\/tags?post=32778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}